{"id":17997,"date":"2025-02-03T06:52:43","date_gmt":"2025-02-03T11:52:43","guid":{"rendered":"https:\/\/tribu.la\/?p=17997"},"modified":"2026-05-14T13:56:21","modified_gmt":"2026-05-14T17:56:21","slug":"lever-vc-secures-50-million-in-first-close-of-fund-ii-for-agrifood-tech-investments","status":"publish","type":"post","link":"https:\/\/tribu.la\/es\/lever-vc-secures-50-million-in-first-close-of-fund-ii-for-agrifood-tech-investments\/","title":{"rendered":"Lever VC consigue $50 millones en el primer cierre del Fondo II para inversiones en tecnolog\u00eda agroalimentaria"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.levervc.com\/\" title=\"\">Palanca VC<\/a> ha anunciado el primer cierre de su segundo fondo de inversi\u00f3n, con el que ha recaudado $50 millones para apoyar a empresas incipientes del sector de la tecnolog\u00eda agroalimentaria. La empresa de capital riesgo, que opera desde Estados Unidos y Hong Kong, est\u00e1 especializada en identificar y respaldar empresas innovadoras centradas en avances alimentarios y agr\u00edcolas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fondo sigue abierto a nuevos inversores y se espera que alcance su cierre definitivo en 2025. La base de inversores incluye inversores institucionales, fondos de fondos, family offices y grandes empresas agroalimentarias de varios continentes. El objetivo del Fondo II es capitalizar las oportunidades emergentes en el sector de la tecnolog\u00eda agroalimentaria, un \u00e1rea reconocida por su considerable tama\u00f1o de mercado, sus fuertes tasas de crecimiento y su activo panorama inversor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lever VC ya ha desplegado capital del Fondo II en cinco empresas que operan en distintos segmentos de la industria:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tecnolog\u00edas Gavan<\/strong> - Desarrolla grasas alternativas para aplicaciones alimentarias.<\/li>\n\n\n\n<li><strong>Oobli<\/strong> - Especializada en prote\u00ednas dulces como alternativas al az\u00facar.<\/li>\n\n\n\n<li><strong>Flox AI<\/strong> - Ofrece soluciones digitales para la agricultura de precisi\u00f3n.<\/li>\n\n\n\n<li><strong>HerdDogg<\/strong> - Se centra en la vigilancia del ganado y la gesti\u00f3n de reba\u00f1os.<\/li>\n\n\n\n<li><strong>Alimentos con setas<\/strong> - Produce ingredientes para alternativas a la carne.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Desde su fundaci\u00f3n, el equipo de inversi\u00f3n de Lever VC ha estado activo en el sector de la alimentaci\u00f3n y la agrotecnolog\u00eda, participando en m\u00e1s de 100 operaciones e invirtiendo m\u00e1s de $500 millones. La firma cuenta con un historial de apoyo a startups en el espacio de las prote\u00ednas alternativas, habiendo respaldado anteriormente a empresas como Beyond Meat, Impossible Foods y Memphis Meats.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nick Cooney, socio director de Lever VC, destac\u00f3 el potencial del sector agroalimentario, citando su escala econ\u00f3mica y sus constantes oportunidades de salida. El objetivo de la empresa es aprovechar su experiencia para generar rendimientos al tiempo que fomenta los avances tecnol\u00f3gicos en la producci\u00f3n de alimentos y la eficiencia agr\u00edcola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La industria agroalimentaria sigue evolucionando, con un aumento de la inversi\u00f3n en soluciones alimentarias sostenibles y escalables. El \u00faltimo fondo de Lever VC refleja el creciente inter\u00e9s de los inversores que buscan impulsar la innovaci\u00f3n en la producci\u00f3n de alimentos, las cadenas de suministro y las prote\u00ednas alternativas. A medida que el Fondo II avanza hacia su cierre definitivo, se espera que siga ampliando su cartera con inversiones adicionales en tecnolog\u00edas agroalimentarias transformadoras.<\/p>","protected":false},"excerpt":{"rendered":"<p>Lever VC consigue $50 millones en el primer cierre del Fondo II para invertir en startups de tecnolog\u00eda agroalimentaria en fase inicial a escala mundial.<\/p>","protected":false},"author":16,"featured_media":17998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[332,410],"tags":[321,369],"content_format":[1037],"class_list":["post-17997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-tribu","tag-funding","tag-venture-capital","content_format-article"],"acf":{"content_format":1037},"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/tribu.la\/wp-content\/uploads\/2025\/02\/levervc-field.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:03:17","action":"category","newStatus":"draft","terms":[337],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/17997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/comments?post=17997"}],"version-history":[{"count":1,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/17997\/revisions"}],"predecessor-version":[{"id":17999,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/17997\/revisions\/17999"}],"acf:term":[{"embeddable":true,"taxonomy":"content_format","href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/content_format\/1037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/media\/17998"}],"wp:attachment":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/media?parent=17997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/categories?post=17997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/tags?post=17997"},{"taxonomy":"content_format","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/content_format?post=17997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}