{"id":16379,"date":"2024-09-27T16:12:54","date_gmt":"2024-09-27T20:12:54","guid":{"rendered":"https:\/\/tribu.la\/?p=16379"},"modified":"2026-05-14T13:58:14","modified_gmt":"2026-05-14T17:58:14","slug":"global-survey-highlights-farmers-concerns-about-climate-change-and-adoption-of-new-technologies","status":"publish","type":"post","link":"https:\/\/tribu.la\/es\/global-survey-highlights-farmers-concerns-about-climate-change-and-adoption-of-new-technologies\/","title":{"rendered":"Una encuesta mundial destaca la preocupaci\u00f3n de los agricultores por el cambio clim\u00e1tico y la adopci\u00f3n de nuevas tecnolog\u00edas"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Un nuevo <a href=\"https:\/\/www.bayer.com\/sites\/default\/files\/farmervoice2024-report-digital-final.pdf\" title=\"\">encuesta<\/a> ha revelado que 75% de los agricultores ya se ven afectados por el cambio clim\u00e1tico o est\u00e1n preocupados por sus efectos, y 71% se\u00f1alan la reducci\u00f3n de los rendimientos como un reto importante. La encuesta 2024 Farmer Voice, realizada por Kynetec en nombre de Bayer, recogi\u00f3 datos de 2.000 agricultores de ocho pa\u00edses: Alemania, Australia, Brasil, China, Estados Unidos, India, Kenia y Ucrania. El estudio pone de relieve las dificultades a las que se enfrentan los agricultores, como los fen\u00f3menos meteorol\u00f3gicos extremos, la inestabilidad pol\u00edtica y la volatilidad econ\u00f3mica. En particular, el 60% de los encuestados ha experimentado p\u00e9rdidas de ingresos debido a condiciones meteorol\u00f3gicas inusuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los agricultores buscan cada vez m\u00e1s la innovaci\u00f3n como parte de la soluci\u00f3n, y 75% expresan su apertura a la adopci\u00f3n de nuevas tecnolog\u00edas para mejorar su resiliencia ante los retos relacionados con el clima. En Brasil, los agricultores se centran especialmente en las herramientas digitales para optimizar sus operaciones agr\u00edcolas. A nivel mundial, casi dos tercios de los agricultores ya utilizan tecnolog\u00edas digitales, y otros 25% tienen previsto adoptarlas. Las principales motivaciones para utilizar estas herramientas son factores econ\u00f3micos como la mejora del rendimiento de los cultivos, el ahorro de costes y la mejora de la calidad de las cosechas. Sin embargo, persiste la brecha digital, especialmente en pa\u00edses como la India, donde s\u00f3lo 8% de los agricultores utilizan actualmente herramientas digitales, aunque 85% tienen previsto aplicarlas en el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La encuesta tambi\u00e9n pone de relieve el creciente inter\u00e9s por la sostenibilidad y las pr\u00e1cticas agr\u00edcolas regenerativas. M\u00e1s de 90% de los agricultores de todo el mundo emplean al menos un m\u00e9todo regenerativo, siendo pr\u00e1cticas como la rotaci\u00f3n de cultivos y el control de la salud del suelo las m\u00e1s comunes. Estas pr\u00e1cticas est\u00e1n en consonancia con los objetivos de los agricultores de aumentar la productividad manteniendo la viabilidad de las explotaciones a largo plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la encuesta mundial, se realiz\u00f3 otro estudio con peque\u00f1os agricultores de India e Indonesia. Ambos grupos informaron de que se enfrentan a un aumento de los costes de los insumos y a retos relacionados con el cambio clim\u00e1tico. A pesar de estas dificultades, los agricultores de estas regiones, al igual que los de Am\u00e9rica Latina, mantienen el optimismo sobre su trabajo, y la mayor\u00eda expresa orgullo por su papel a la hora de garantizar la seguridad alimentaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puede descargar los resultados de la encuesta <a href=\"https:\/\/www.bayer.com\/sites\/default\/files\/farmervoice2024-report-digital-final.pdf\" title=\"\">aqu\u00ed<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una encuesta mundial revela la preocupaci\u00f3n de los agricultores por el cambio clim\u00e1tico, la reducci\u00f3n de los rendimientos y la creciente adopci\u00f3n de pr\u00e1cticas digitales y regenerativas.<\/p>","protected":false},"author":16,"featured_media":16380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[332,410],"tags":[317,379],"content_format":[1037],"class_list":["post-16379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-tribu","tag-agtech","tag-market-trends","content_format-article"],"acf":{"content_format":1037},"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/tribu.la\/wp-content\/uploads\/2024\/09\/farmervoice.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 15:50:23","action":"category","newStatus":"draft","terms":[337],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/16379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/comments?post=16379"}],"version-history":[{"count":1,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/16379\/revisions"}],"predecessor-version":[{"id":16381,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/16379\/revisions\/16381"}],"acf:term":[{"embeddable":true,"taxonomy":"content_format","href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/content_format\/1037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/media\/16380"}],"wp:attachment":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/media?parent=16379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/categories?post=16379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/tags?post=16379"},{"taxonomy":"content_format","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/content_format?post=16379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}