{"id":16032,"date":"2024-09-05T14:26:00","date_gmt":"2024-09-05T18:26:00","guid":{"rendered":"https:\/\/tribu.la\/?p=16032"},"modified":"2024-09-05T14:26:56","modified_gmt":"2024-09-05T18:26:56","slug":"rappi-adquiere-la-empresa-india-de-ai-para-la-cadena-de-suministro-fountain9","status":"publish","type":"post","link":"https:\/\/tribu.la\/es\/rappi-acquires-indian-ai-supply-chain-firm-fountain9\/","title":{"rendered":"Rappi adquiere la empresa india de IA para la cadena de suministro Fountain9"},"content":{"rendered":"<p>Operador de reparto a la carta <a href=\"https:\/\/www.rappi.com\/\" title=\"\">Rappi<\/a>ha adquirido los activos de <a href=\"https:\/\/www.fountain9.com\/\" title=\"\">Fuente9<\/a>una empresa india especializada en soluciones para la cadena de suministro basadas en inteligencia artificial. La operaci\u00f3n abarca la propiedad intelectual de Fountain9 y su equipo, aunque no se han revelado los detalles financieros.<\/p>\n\n\n\n<p>Fountain9 es reconocida por su plataforma de planificaci\u00f3n de inventario impulsada por IA, que mejora la eficiencia de la cadena de suministro a trav\u00e9s de la previsi\u00f3n avanzada de la demanda, la optimizaci\u00f3n de precios y la reducci\u00f3n de residuos. La plataforma ha mejorado significativamente las operaciones de la cadena de suministro de varias empresas aprovechando el aprendizaje autom\u00e1tico para el an\u00e1lisis predictivo.<\/p>\n\n\n\n<p>La adquisici\u00f3n se produce tras una fruct\u00edfera colaboraci\u00f3n entre Rappi y Fountain9, en la que la tecnolog\u00eda de esta \u00faltima fue decisiva para optimizar las operaciones de entrega de Rappi Turbo. Esta experiencia positiva sent\u00f3 unas bases de confianza que allanaron el camino para la compra de activos.<\/p>\n\n\n\n<p>Felipe Villamar\u00edn, cofundador de Rappi, ha destacado que esta adquisici\u00f3n es un movimiento estrat\u00e9gico para avanzar en las capacidades tecnol\u00f3gicas de la compa\u00f1\u00eda en la gesti\u00f3n de la cadena de suministro. \"La integraci\u00f3n de los activos de Fountain9 nos permite aprovechar a\u00fan m\u00e1s la IA para mejorar nuestras operaciones en la cadena de suministro y ampliar estas capacidades a nuestros socios\", declar\u00f3 Villamar\u00edn.<\/p>\n\n\n\n<p>Como parte de la adquisici\u00f3n, los cofundadores de Fountain9, Niki Khokale y Rajas Lonkar, junto con su equipo, se unir\u00e1n a Rappi. Se espera que este movimiento refuerce las operaciones de entrega de Rappi en Am\u00e9rica Latina y posicione a la empresa como un centro global para los mejores talentos en tecnolog\u00eda y gesti\u00f3n de la cadena de suministro.<\/p>","protected":false},"excerpt":{"rendered":"<p>Rappi ha adquirido los activos de Fountain9, incluida la propiedad intelectual y el equipo, para mejorar sus operaciones de cadena de suministro impulsadas por IA.<\/p>","protected":false},"author":16,"featured_media":16033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[332,410],"tags":[229,245,378,320,295],"class_list":["post-16032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-tribu","tag-colombia","tag-food-delivery","tag-logistics","tag-startup","tag-supply-chains"],"acf":{"content_format":false},"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/tribu.la\/wp-content\/uploads\/2024\/09\/fountain9.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:23:31","action":"category","newStatus":"draft","terms":[337],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/16032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/comments?post=16032"}],"version-history":[{"count":1,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/16032\/revisions"}],"predecessor-version":[{"id":16034,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/16032\/revisions\/16034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/media\/16033"}],"wp:attachment":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/media?parent=16032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/categories?post=16032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/tags?post=16032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}