{"id":15507,"date":"2024-08-02T10:30:22","date_gmt":"2024-08-02T14:30:22","guid":{"rendered":"https:\/\/tribu.la\/?p=15507"},"modified":"2024-08-13T10:39:31","modified_gmt":"2024-08-13T14:39:31","slug":"nueva-base-de-datos-nacional-sobre-el-indice-glucemico-para-la-calidad-de-los-hidratos-de-carbono-en-ee-uu","status":"publish","type":"post","link":"https:\/\/tribu.la\/es\/new-national-glycemic-index-database-developed-for-u-s-carbohydrate-quality\/","title":{"rendered":"Nueva base de datos nacional sobre el \u00edndice gluc\u00e9mico para la calidad de los carbohidratos en EE.UU."},"content":{"rendered":"<p class=\"wp-block-paragraph\">Karen Della Corte, catedr\u00e1tica de nutrici\u00f3n y diet\u00e9tica de la Universidad Brigham Young (BYU), ha dirigido una <a href=\"http:\/\/dx.doi.org\/10.1016\/j.ajcnut.2024.06.001\" title=\"\">estudiar<\/a> que introduce una base de datos nacional sobre el \u00edndice gluc\u00e9mico (IG) y la carga gluc\u00e9mica (CG), publicada recientemente en <em>La revista American Journal of Clinical Nutrition<\/em>. Esta iniciativa representa el primer esfuerzo global para rastrear y analizar la calidad de los carbohidratos consumidos en todo Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00edndice gluc\u00e9mico es una medida que clasifica los hidratos de carbono en funci\u00f3n de su impacto en los niveles de az\u00facar en sangre. Los alimentos con un IG elevado, como la harina blanca y los cereales azucarados, pueden provocar un r\u00e1pido aumento de la glucosa en sangre, lo que puede afectar negativamente a la salud metab\u00f3lica. La carga gluc\u00e9mica, que tiene en cuenta tanto la calidad como la cantidad de hidratos de carbono, contribuye a\u00fan m\u00e1s a comprender los efectos de la dieta sobre la salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Las dietas con IG y CG elevados se han relacionado con un mayor riesgo de diabetes de tipo 2, enfermedades cardiovasculares y ciertos tipos de c\u00e1ncer\", se\u00f1al\u00f3 Della Corte. \"Estas dietas tambi\u00e9n pueden provocar una aparici\u00f3n m\u00e1s r\u00e1pida del hambre, un aumento de la ingesta cal\u00f3rica y el consiguiente aumento de peso\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para crear la base de datos, Della Corte, junto con su marido Dennis Della Corte, profesor de f\u00edsica y astronom\u00eda en la BYU, emplearon un modelo basado en inteligencia artificial para analizar los datos sobre carbohidratos. Utilizaron la Encuesta Nacional de Salud y Nutrici\u00f3n (NHANES), que proporciona una lista exhaustiva de los alimentos consumidos por los estadounidenses. El sistema de IA emparej\u00f3 estos alimentos con sus correspondientes valores de IG y CG, lo que dio lugar a la creaci\u00f3n de la primera base de datos nacional de IG.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Este uso de la IA en la generaci\u00f3n de la base de datos del IG representa un avance metodol\u00f3gico significativo en la investigaci\u00f3n nutricional\", declar\u00f3 Della Corte. \"Este recurso abre nuevas v\u00edas para explorar el papel del IG y la GL en los riesgos de enfermedades cr\u00f3nicas dentro de los EE.UU.\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La base de datos permiti\u00f3 analizar la calidad de los carbohidratos en casi 10.000 alimentos. Lo que habr\u00eda sido un proceso largo se agiliz\u00f3 gracias a la tecnolog\u00eda de IA, lo que permiti\u00f3 examinar las tendencias diet\u00e9ticas de las dos \u00faltimas d\u00e9cadas. El estudio puso de relieve los principales factores que contribuyen a la carga gluc\u00e9mica de la dieta, como los refrescos, el pan blanco, el arroz y los zumos de fruta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Della Corte destac\u00f3 los beneficios de centrarse en los carbohidratos de bajo \u00edndice gluc\u00e9mico, recomendando la inclusi\u00f3n en la dieta de cereales integrales, alubias, lentejas y verduras sin almid\u00f3n. Estas opciones pueden mitigar los picos de az\u00facar en sangre y contribuir a mejorar la salud en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n tambi\u00e9n identific\u00f3 variaciones en los patrones diet\u00e9ticos de IG y CG en funci\u00f3n del sexo, la raza, la etnia, la educaci\u00f3n y los ingresos. Los resultados revelaron que las personas de m\u00e1s edad y las de mayor nivel educativo e ingresos tienden a elegir carbohidratos m\u00e1s saludables. Se observ\u00f3 que los adultos de raza negra y las mujeres ten\u00edan niveles m\u00e1s altos de IG y CG en comparaci\u00f3n con otros grupos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio, en el que tambi\u00e9n han participado Sean Titensor, estudiante universitario de la BYU, y la Dra. Simin Liu, de la Universidad de Brown, pretende mejorar la comprensi\u00f3n p\u00fablica de la calidad de los carbohidratos. Los Della Cortes esperan que esta base de datos sirva de apoyo a futuras investigaciones e influya potencialmente en las directrices de salud p\u00fablica y las recomendaciones diet\u00e9ticas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una nueva base de datos nacional sobre el \u00edndice gluc\u00e9mico analiza la calidad de los carbohidratos y su asociaci\u00f3n con los riesgos para la salud, lo que supone un importante avance.<\/p>","protected":false},"author":16,"featured_media":15508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[723],"tags":[271,288],"content_format":[],"class_list":["post-15507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-science","tag-health-wellness","tag-nutrition"],"acf":{"content_format":false},"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/tribu.la\/wp-content\/uploads\/2024\/08\/lentils.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 07:11:05","action":"category","newStatus":"draft","terms":[337],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/15507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/comments?post=15507"}],"version-history":[{"count":1,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/15507\/revisions"}],"predecessor-version":[{"id":15509,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/posts\/15507\/revisions\/15509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/media\/15508"}],"wp:attachment":[{"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/media?parent=15507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/categories?post=15507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/tags?post=15507"},{"taxonomy":"content_format","embeddable":true,"href":"https:\/\/tribu.la\/es\/wp-json\/wp\/v2\/content_format?post=15507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}